{"id":1401,"date":"2020-11-29T06:44:57","date_gmt":"2020-11-29T06:44:57","guid":{"rendered":"https:\/\/motorcyclechain.top\/spiral-bevel-right-angle-dc-gear-motor-80-90-104mm-25250w\/"},"modified":"2020-11-29T06:44:57","modified_gmt":"2020-11-29T06:44:57","slug":"spiral-bevel-right-angle-dc-gear-motor-80-90-104mm-25250w","status":"publish","type":"post","link":"https:\/\/motorcyclechain.top\/pt\/spiral-bevel-right-angle-dc-gear-motor-80-90-104mm-25250w\/","title":{"rendered":"Motorredutor CC de \u00e2ngulo reto com engrenagem helicoidal, 80, 90, 104 mm, 25~250 W"},"content":{"rendered":"<p><img decoding=\"async\" style=\"height:auto\" title=\"Motorredutor CC de \u00e2ngulo reto com engrenagem helicoidal, 80, 90, 104 mm, 25~250 W\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/motor-base-1.jpg\" alt=\"Motorredutor CC de \u00e2ngulo reto com engrenagem helicoidal, 80, 90, 104 mm, 25~250 W\" \/><\/p>\n<p><p>                                    <strong>Motorredutor CC de \u00e2ngulo pr\u00f3prio com engrenagem helicoidal, 80, 90, 104 mm, 25 a 250 W<\/strong><\/p>\n<p><strong>Caracter\u00edsticas:<\/strong><br \/>1) Propor\u00e7\u00f5es: 80 mm, 90 mm, 104 mm<br \/>dois) Energia: 25, 40, 60, 90, 120, 140W, 180W<br \/>tr\u00eas) Tens\u00e3o (V): 110V, 220V<br \/>4) Velocidade nominal (nS): 1350 rpm, 1550 rpm<br \/>5) Rela\u00e7\u00e3o de redu\u00e7\u00e3o: 50RC, 50RT<\/p>\n<p><strong>Utiliza\u00e7\u00e3o:<\/strong><br \/>Nossos motores CA podem ser amplamente utilizados em equipamentos de sa\u00fade, mecanismos de embalagem, mecanismos de impress\u00e3o, m\u00e1quinas de fabrica\u00e7\u00e3o de copos, m\u00e1quinas t\u00eaxteis, entre outros.<\/p>\n<p>Certifica\u00e7\u00f5es: CE, UL, CZPT e RoHS.<\/p>\n<p><strong>Detalhes da empresa<\/strong><\/p>\n<p><strong>Perguntas frequentes<\/strong><br \/><strong>P: Quais s\u00e3o os seus principais produtos?<\/strong><br \/>A: Atualmente, produzimos motores CC com escovas, motores CC com escovas para equipamentos, motores CC com engrenagens planet\u00e1rias, motores CC sem escovas, motores de passo, motores CA e caixas de engrenagens planet\u00e1rias de alta precis\u00e3o, entre outros. Voc\u00ea pode consultar as especifica\u00e7\u00f5es dos motores mencionados anteriormente em nosso site e tamb\u00e9m pode nos enviar um e-mail para que possamos recomendar os motores adequados \u00e0s suas necessidades.<\/p>\n<p><strong>P: Como escolher o motor adequado?<\/strong><br \/>A: Se voc\u00ea tiver imagens ou desenhos do motor para nos mostrar, ou especifica\u00e7\u00f5es detalhadas como voltagem, velocidade, torque, tamanho do motor, m\u00e9todo de opera\u00e7\u00e3o, vida \u00fatil estimada, n\u00edvel de ru\u00eddo e assim por diante, n\u00e3o hesite em nos informar. Assim, poderemos recomendar o motor mais adequado \u00e0 sua necessidade.<\/p>\n<p><strong>P: Voc\u00eas oferecem servi\u00e7o de ret\u00edfica de tubos de alta press\u00e3o (CZPT) para os motores mais comuns?<\/strong><br \/>R: Sim, podemos personalizar conforme sua solicita\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0 voltagem, velocidade, torque e tamanho\/formato do eixo. Se desejar fios\/cabos extras soldados no terminal ou precisar incluir conectores, capacitores ou componentes EMC, tamb\u00e9m podemos providenciar.<\/p>\n<p><strong>P: Voc\u00eas t\u00eam algum tipo de suporte personalizado para motores?<\/strong><br \/>A: Claro, gostar\u00edamos de projetar motores individualmente para nossos clientes, mas isso pode acarretar custos de desenvolvimento de moldes e taxas de design.\u00a0<\/p>\n<p><strong>P: Qual \u00e9, de fato, o prazo de entrega?<\/strong><br \/>A: Em termos gerais, nossos produtos regulares da CZPT precisam de 15 a 30 dias para serem entregues, sendo que os produtos da CZPT podem levar um pouco mais de tempo. No entanto, somos extremamente flex\u00edveis quanto ao prazo de entrega, que depender\u00e1 de cada pedido espec\u00edfico.<\/p>\n<p><strong>Entre em contato conosco se tiver alguma solicita\u00e7\u00e3o mais detalhada, obrigado!<\/strong>                            <\/p>\n<p>\n<p><img decoding=\"async\" style=\"height:auto\" title=\"Motorredutor CC de \u00e2ngulo reto com engrenagem helicoidal, 80, 90, 104 mm, 25~250 W\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/motor-base-2.jpg\" alt=\"Motorredutor CC de \u00e2ngulo reto com engrenagem helicoidal, 80, 90, 104 mm, 25~250 W\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>sprial bevel proper angle, dc gear motor ,80.90.104mm,twenty five~250W Characteristics:one) Proportions: 80mm, 90mm, 104mmtwo) Energy: 25, 40, 60, ninety, 120, 140W, 180Wthree) Voltage(v): 110V, 220V4) Rated Speed(nS): 1350rpm, 1550rpm5) Reduction ratio: 50RC, 50RT Utilization:Our ac equipment motors can be widely employed in healthcare appliance, packing mechanism, printing mechanism, cup generating machine, textile machinery, and so [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1401","post","type-post","status-publish","format-standard","hentry","category-product-catalog"],"_links":{"self":[{"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/posts\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":0,"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/posts\/1401\/revisions"}],"wp:attachment":[{"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/media?parent=1401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/categories?post=1401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/motorcyclechain.top\/pt\/wp-json\/wp\/v2\/tags?post=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}